
{"id":53770,"date":"2026-01-20T16:07:12","date_gmt":"2026-01-20T16:07:12","guid":{"rendered":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1.jpg"},"modified":"2026-01-20T16:07:12","modified_gmt":"2026-01-20T16:07:12","slug":"sala-1-6-2","status":"inherit","type":"attachment","link":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/","title":{"rendered":"Sala 1"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-53770","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gabi Miguel Rentals \u2022 Your choice for all seasons\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sala 1 \u2022 Gabi Miguel Rentals\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"138\" \/>\n\t\t<meta property=\"og:image:height\" content=\"44\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-01-20T16:07:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-20T16:07:12+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gmholidayrentals\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sala 1 \u2022 Gabi Miguel Rentals\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/accommodation\\\/villa-natura\\\/sala-1-6-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/accommodation\\\/villa-natura\\\/sala-1-6-2\\\/#listItem\",\"name\":\"Sala 1\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/accommodation\\\/villa-natura\\\/sala-1-6-2\\\/#listItem\",\"position\":2,\"name\":\"Sala 1\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/accommodation\\\/villa-natura\\\/sala-1-6-2\\\/#itempage\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/accommodation\\\/villa-natura\\\/sala-1-6-2\\\/\",\"name\":\"Sala 1 \\u2022 Gabi Miguel Rentals\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/accommodation\\\/villa-natura\\\/sala-1-6-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-01-20T16:07:12+00:00\",\"dateModified\":\"2026-01-20T16:07:12+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/#organization\",\"name\":\"Gabi Miguel\",\"description\":\"Your choice for all seasons\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/\",\"telephone\":\"+351289591378\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Gabi-Miguel-Holiday-Rentals.png\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/accommodation\\\/villa-natura\\\/sala-1-6-2\\\/#organizationLogo\",\"width\":138,\"height\":44},\"image\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/accommodation\\\/villa-natura\\\/sala-1-6-2\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gmholidayrentals\",\"https:\\\/\\\/www.instagram.com\\\/gm_holiday_rentals\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCcljMtn3tGtMKLrHu6bEgiA\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/gabimiguel\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/author\\\/admin\\\/\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/accommodation\\\/villa-natura\\\/sala-1-6-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/068b65d24f062718562080b91a2711d10b0ceca66e352ff12b26021012f494c2?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Admin\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/\",\"name\":\"Gabi Miguel Holiday Rentals\",\"alternateName\":\"Gabi Miguel\",\"description\":\"Your choice for all seasons\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sala 1 \u2022 Gabi Miguel Rentals","description":"","canonical_url":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/gabimiguel.pt\/rentals\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/#listItem","name":"Sala 1"}},{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/#listItem","position":2,"name":"Sala 1","previousItem":{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/de\/#listItem","name":"Home"}}]},{"@type":"ItemPage","@id":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/#itempage","url":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/","name":"Sala 1 \u2022 Gabi Miguel Rentals","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/gabimiguel.pt\/rentals\/de\/#website"},"breadcrumb":{"@id":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/#breadcrumblist"},"author":{"@id":"https:\/\/gabimiguel.pt\/rentals\/de\/author\/admin\/#author"},"creator":{"@id":"https:\/\/gabimiguel.pt\/rentals\/de\/author\/admin\/#author"},"datePublished":"2026-01-20T16:07:12+00:00","dateModified":"2026-01-20T16:07:12+00:00"},{"@type":"Organization","@id":"https:\/\/gabimiguel.pt\/rentals\/de\/#organization","name":"Gabi Miguel","description":"Your choice for all seasons","url":"https:\/\/gabimiguel.pt\/rentals\/de\/","telephone":"+351289591378","logo":{"@type":"ImageObject","url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png","@id":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/#organizationLogo","width":138,"height":44},"image":{"@id":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/gmholidayrentals","https:\/\/www.instagram.com\/gm_holiday_rentals\/","https:\/\/www.youtube.com\/channel\/UCcljMtn3tGtMKLrHu6bEgiA","https:\/\/www.linkedin.com\/in\/gabimiguel\/"]},{"@type":"Person","@id":"https:\/\/gabimiguel.pt\/rentals\/de\/author\/admin\/#author","url":"https:\/\/gabimiguel.pt\/rentals\/de\/author\/admin\/","name":"Admin","image":{"@type":"ImageObject","@id":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/068b65d24f062718562080b91a2711d10b0ceca66e352ff12b26021012f494c2?s=96&d=mm&r=g","width":96,"height":96,"caption":"Admin"}},{"@type":"WebSite","@id":"https:\/\/gabimiguel.pt\/rentals\/de\/#website","url":"https:\/\/gabimiguel.pt\/rentals\/de\/","name":"Gabi Miguel Holiday Rentals","alternateName":"Gabi Miguel","description":"Your choice for all seasons","inLanguage":"de-DE","publisher":{"@id":"https:\/\/gabimiguel.pt\/rentals\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Gabi Miguel Rentals \u2022 Your choice for all seasons","og:type":"article","og:title":"Sala 1 \u2022 Gabi Miguel Rentals","og:url":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/","og:image":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png","og:image:secure_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png","og:image:width":138,"og:image:height":44,"article:published_time":"2026-01-20T16:07:12+00:00","article:modified_time":"2026-01-20T16:07:12+00:00","article:publisher":"https:\/\/www.facebook.com\/gmholidayrentals","twitter:card":"summary_large_image","twitter:title":"Sala 1 \u2022 Gabi Miguel Rentals","twitter:image":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png"},"aioseo_meta_data":{"post_id":"53770","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-01-20 16:25:16","updated":"2026-01-20 16:25:16","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gabimiguel.pt\/rentals\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSala 1\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/gabimiguel.pt\/rentals\/de\/"},{"label":"Sala 1","link":"https:\/\/gabimiguel.pt\/rentals\/de\/accommodation\/villa-natura\/sala-1-6-2\/"}],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-300x200.jpg 300w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-1024x683.jpg 1024w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-768x512.jpg 768w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-1536x1024.jpg 1536w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-2048x1365.jpg 2048w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-2000x1333.jpg 2000w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-927x618.jpg 927w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1707,"file":"2021\/01\/Sala-1-scaled.jpg","filesize":466481,"sizes":{"medium":{"file":"Sala-1-300x200.jpg","width":300,"height":200,"filesize":11705,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-300x200.jpg"},"large":{"file":"Sala-1-1024x683.jpg","width":1024,"height":683,"filesize":87560,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-1024x683.jpg"},"thumbnail":{"file":"Sala-1-150x150.jpg","width":150,"height":150,"filesize":5835,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-150x150.jpg"},"medium_large":{"file":"Sala-1-768x512.jpg","width":768,"height":512,"filesize":52459,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-768x512.jpg"},"1536x1536":{"file":"Sala-1-1536x1024.jpg","width":1536,"height":1024,"filesize":181565,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-1536x1024.jpg"},"2048x2048":{"file":"Sala-1-2048x1365.jpg","width":2048,"height":1365,"filesize":311128,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-2048x1365.jpg"},"post-thumbnail":{"file":"Sala-1-1434x734.jpg","width":1434,"height":734,"filesize":133985,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-1434x734.jpg"},"villagio-thumb-large":{"file":"Sala-1-2000x1333.jpg","width":2000,"height":1333,"filesize":299902,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-2000x1333.jpg"},"villagio-thumb-medium":{"file":"Sala-1-927x618.jpg","width":927,"height":618,"filesize":73479,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-927x618.jpg"},"villagio-thumb-small":{"file":"Sala-1-717x540.jpg","width":717,"height":540,"filesize":54114,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-717x540.jpg"},"villagio-thumb-small-x2":{"file":"Sala-1-1434x1080.jpg","width":1434,"height":1080,"filesize":189266,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-1434x1080.jpg"},"full":{"file":"Sala-1-scaled.jpg","width":2560,"height":1707,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]},"original_image":"Sala-1.jpg"},"post":19088,"source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2021\/01\/Sala-1-scaled.jpg","filename":"Sala-1.jpg","filesize":466481,"_links":{"self":[{"href":"https:\/\/gabimiguel.pt\/rentals\/de\/wp-json\/wp\/v2\/media\/53770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gabimiguel.pt\/rentals\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/gabimiguel.pt\/rentals\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/gabimiguel.pt\/rentals\/de\/wp-json\/wp\/v2\/users\/1"}],"wp:attached-to":[{"embeddable":true,"post_type":"mphb_room_type","id":19088,"href":"https:\/\/gabimiguel.pt\/rentals\/de\/wp-json\/wp\/v2\/mphb_room_type\/19088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}