
{"id":8792,"date":"2020-12-28T15:59:57","date_gmt":"2020-12-28T15:59:57","guid":{"rendered":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads%20panoramica\/Panoramica%20-%20exterior4.jpg"},"modified":"2020-12-28T15:59:57","modified_gmt":"2020-12-28T15:59:57","slug":"panoramica-exterior4-2","status":"inherit","type":"attachment","link":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/","title":{"rendered":"Panoramica &#8211; exterior4"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-8792","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_PT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gabi Miguel Rentals \u2022 Your choice for all seasons\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Panoramica \u2013 exterior4 \u2022 Gabi Miguel Rentals\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"138\" \/>\n\t\t<meta property=\"og:image:height\" content=\"44\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-12-28T15:59:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-12-28T15:59:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gmholidayrentals\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Panoramica \u2013 exterior4 \u2022 Gabi Miguel Rentals\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/panoramica-exterior4-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/panoramica-exterior4-2\\\/#listItem\",\"name\":\"Panoramica &#8211; exterior4\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/panoramica-exterior4-2\\\/#listItem\",\"position\":2,\"name\":\"Panoramica &#8211; exterior4\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/panoramica-exterior4-2\\\/#itempage\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/panoramica-exterior4-2\\\/\",\"name\":\"Panoramica \\u2013 exterior4 \\u2022 Gabi Miguel Rentals\",\"inLanguage\":\"pt-PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/panoramica-exterior4-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2020-12-28T15:59:57+00:00\",\"dateModified\":\"2020-12-28T15:59:57+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/#organization\",\"name\":\"Gabi Miguel\",\"description\":\"Your choice for all seasons\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/\",\"telephone\":\"+351289591378\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Gabi-Miguel-Holiday-Rentals.png\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/panoramica-exterior4-2\\\/#organizationLogo\",\"width\":138,\"height\":44},\"image\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/panoramica-exterior4-2\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gmholidayrentals\",\"https:\\\/\\\/www.instagram.com\\\/gm_holiday_rentals\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCcljMtn3tGtMKLrHu6bEgiA\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/gabimiguel\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/author\\\/admin\\\/\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/panoramica-exterior4-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/068b65d24f062718562080b91a2711d10b0ceca66e352ff12b26021012f494c2?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Admin\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/\",\"name\":\"Gabi Miguel Holiday Rentals\",\"alternateName\":\"Gabi Miguel\",\"description\":\"Your choice for all seasons\",\"inLanguage\":\"pt-PT\",\"publisher\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Panoramica \u2013 exterior4 \u2022 Gabi Miguel Rentals","description":"","canonical_url":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/#listItem","position":1,"name":"Home","item":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/#listItem","name":"Panoramica &#8211; exterior4"}},{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/#listItem","position":2,"name":"Panoramica &#8211; exterior4","previousItem":{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/#listItem","name":"Home"}}]},{"@type":"ItemPage","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/#itempage","url":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/","name":"Panoramica \u2013 exterior4 \u2022 Gabi Miguel Rentals","inLanguage":"pt-PT","isPartOf":{"@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/#website"},"breadcrumb":{"@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/#breadcrumblist"},"author":{"@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/author\/admin\/#author"},"creator":{"@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/author\/admin\/#author"},"datePublished":"2020-12-28T15:59:57+00:00","dateModified":"2020-12-28T15:59:57+00:00"},{"@type":"Organization","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/#organization","name":"Gabi Miguel","description":"Your choice for all seasons","url":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/","telephone":"+351289591378","logo":{"@type":"ImageObject","url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/#organizationLogo","width":138,"height":44},"image":{"@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/gmholidayrentals","https:\/\/www.instagram.com\/gm_holiday_rentals\/","https:\/\/www.youtube.com\/channel\/UCcljMtn3tGtMKLrHu6bEgiA","https:\/\/www.linkedin.com\/in\/gabimiguel\/"]},{"@type":"Person","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/author\/admin\/#author","url":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/author\/admin\/","name":"Admin","image":{"@type":"ImageObject","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/068b65d24f062718562080b91a2711d10b0ceca66e352ff12b26021012f494c2?s=96&d=mm&r=g","width":96,"height":96,"caption":"Admin"}},{"@type":"WebSite","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/#website","url":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/","name":"Gabi Miguel Holiday Rentals","alternateName":"Gabi Miguel","description":"Your choice for all seasons","inLanguage":"pt-PT","publisher":{"@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/#organization"}}]},"og:locale":"pt_PT","og:site_name":"Gabi Miguel Rentals \u2022 Your choice for all seasons","og:type":"article","og:title":"Panoramica \u2013 exterior4 \u2022 Gabi Miguel Rentals","og:url":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/","og:image":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png","og:image:secure_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png","og:image:width":138,"og:image:height":44,"article:published_time":"2020-12-28T15:59:57+00:00","article:modified_time":"2020-12-28T15:59:57+00:00","article:publisher":"https:\/\/www.facebook.com\/gmholidayrentals","twitter:card":"summary_large_image","twitter:title":"Panoramica \u2013 exterior4 \u2022 Gabi Miguel Rentals","twitter:image":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png"},"aioseo_meta_data":{"post_id":"8792","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-10 10:16:07","updated":"2025-06-05 05:07:56","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPanoramica \u2013 exterior4\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/"},{"label":"Panoramica &#8211; exterior4","link":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/panoramica-exterior4-2\/"}],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads%20panoramica\/Panoramica%20-%20exterior4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads panoramica\/Panoramica - exterior4-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads%20panoramica\/Panoramica%20-%20exterior4-300x200.jpg 300w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads%20panoramica\/Panoramica%20-%20exterior4-1024x683.jpg 1024w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads%20panoramica\/Panoramica%20-%20exterior4-768x512.jpg 768w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads%20panoramica\/Panoramica%20-%20exterior4-1536x1024.jpg 1536w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads%20panoramica\/Panoramica%20-%20exterior4-927x618.jpg 927w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads%20panoramica\/Panoramica%20-%20exterior4.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1280,"file":"2020\/12\/uploads panoramica\/Panoramica - exterior4.jpg","sizes":{"medium":{"file":"Panoramica - exterior4-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads panoramica\/Panoramica - exterior4-300x200.jpg"},"large":{"file":"Panoramica - exterior4-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads panoramica\/Panoramica - exterior4-1024x683.jpg"},"thumbnail":{"file":"Panoramica - exterior4-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads panoramica\/Panoramica - exterior4-150x150.jpg"},"medium_large":{"file":"Panoramica - exterior4-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads panoramica\/Panoramica - exterior4-768x512.jpg"},"1536x1536":{"file":"Panoramica - exterior4-1536x1024.jpg","width":1536,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads panoramica\/Panoramica - exterior4-1536x1024.jpg"},"post-thumbnail":{"file":"Panoramica - exterior4-1434x734.jpg","width":1434,"height":734,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads panoramica\/Panoramica - exterior4-1434x734.jpg"},"villagio-thumb-medium":{"file":"Panoramica - exterior4-927x618.jpg","width":927,"height":618,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads panoramica\/Panoramica - exterior4-927x618.jpg"},"villagio-thumb-small":{"file":"Panoramica - exterior4-717x540.jpg","width":717,"height":540,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads panoramica\/Panoramica - exterior4-717x540.jpg"},"villagio-thumb-small-x2":{"file":"Panoramica - exterior4-1434x1080.jpg","width":1434,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads panoramica\/Panoramica - exterior4-1434x1080.jpg"},"full":{"file":"Panoramica - exterior4.jpg","width":1920,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads panoramica\/Panoramica - exterior4.jpg"}},"image_meta":{"aperture":"5","credit":"","camera":"Canon EOS 760D","caption":"","created_timestamp":"1459522798","copyright":"","focal_length":"14","iso":"125","shutter_speed":"0.001","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2020\/12\/uploads panoramica\/Panoramica - exterior4.jpg","filename":"Panoramica - exterior4.jpg","filesize":214995,"_links":{"self":[{"href":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/media\/8792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/users\/1"}]}}