
{"id":16612,"date":"2023-06-07T13:02:33","date_gmt":"2023-06-07T13:02:33","guid":{"rendered":"https:\/\/gabimiguel.pt\/rentals\/?page_id=16612"},"modified":"2024-08-13T12:35:03","modified_gmt":"2024-08-13T12:35:03","slug":"about-us","status":"publish","type":"page","link":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/","title":{"rendered":"About Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16612\" class=\"elementor elementor-16612\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25e40f0 elementor-section-full_width elementor-section-height-min-height elementor-section-stretched elementor-section-height-default elementor-section-items-middle\" data-id=\"25e40f0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4d1246\" data-id=\"b4d1246\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00a6ae4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00a6ae4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da736dd\" data-id=\"da736dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c264f2 elementor-widget elementor-widget-heading\" data-id=\"5c264f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h2 lang=\"en-US\" style=\"font-family: Lato, sans-serif;white-space: normal\">Gabi Miguel Real Estate, Property Management &amp; Holiday Rentals<\/h2><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fdc201 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9fdc201\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c1fa232\" data-id=\"c1fa232\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1b37ad elementor-widget elementor-widget-heading\" data-id=\"b1b37ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Quer ajuda para rentabilizar, vender ou manter a sua propriedade? Conhe\u00e7a a Gabi Miguel.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ecdc711 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"ecdc711\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bc2c7b4\" data-id=\"bc2c7b4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6062b83 elementor-widget elementor-widget-spacer\" data-id=\"6062b83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b1c12b9\" data-id=\"b1c12b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1f4573 elementor-widget elementor-widget-text-editor\" data-id=\"b1f4573\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fundada em 1987, a Gabi Miguel Lda est\u00e1 situada em Vale da Parra e se dedica a oferecer as melhores solu\u00e7\u00f5es para clientes na compra\/venda de im\u00f3veis, bem como no aluguer de f\u00e9rias no Algarve.<\/p><p>A equipa \u00e9 internacional e composta por profissionais portugueses e alem\u00e3es que combinados somam mais de 50 anos de experi\u00eancia na \u00e1rea do turismo. Os idiomas falados abrangem portugu\u00eas, alem\u00e3o, ingl\u00eas, franc\u00eas e espanhol.<\/p><p>As acomoda\u00e7\u00f5es em regime de alojamento se diferem de hot\u00e9is e resorts pois s\u00e3o propriedades individuais, mobiladas ao gosto do propriet\u00e1rio e administradas para o aluguer de curta e longa dura\u00e7\u00e3o.<\/p><p>A actividade principal \u00e9 a administra\u00e7\u00e3o de propriedades, com especial dedica\u00e7\u00e3o ao aluguer de vivendas, bem como manuten\u00e7\u00e3o de propriedade, paisag\u00edstica e assist\u00eancia contabil\u00edstica.<\/p><p>O servi\u00e7o de administra\u00e7\u00e3o de propriedade est\u00e1 dispon\u00edvel em toda a parte ocidental de Albufeira, nomeadamente Vale da Parra, Gal\u00e9, P\u00eara, Alcantarilha, Guia, S\u00e3o Rafael e Albufeira.est\u00e1 situada<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ffdd30 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ffdd30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0f0c624\" data-id=\"0f0c624\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ab8fed elementor-widget elementor-widget-spacer\" data-id=\"4ab8fed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c728cc3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c728cc3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c2e5bf\" data-id=\"1c2e5bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08c318a elementor-widget elementor-widget-heading\" data-id=\"08c318a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servi\u00e7os:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b808ed elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b808ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c14acde\" data-id=\"c14acde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04922c8 elementor-widget elementor-widget-spacer\" data-id=\"04922c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b520c3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2b520c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-98d76c6\" data-id=\"98d76c6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91205e1 elementor-widget elementor-widget-spacer\" data-id=\"91205e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ddbb25 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ddbb25\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9e73a0\" data-id=\"b9e73a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b63c870 elementor-widget elementor-widget-spacer\" data-id=\"b63c870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-010c0e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"010c0e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-255c370\" data-id=\"255c370\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ec7f97 elementor-widget elementor-widget-heading\" data-id=\"9ec7f97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gest\u00e3o\/Controlo:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7f916e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7f916e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d74f127\" data-id=\"d74f127\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-301ed00 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"301ed00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-money-bill-wave\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPagamento de contas\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-db03793\" data-id=\"db03793\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d18a8fc elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d18a8fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tshirt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tServi\u00e7o de limpeza e lavandaria\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4acb23c\" data-id=\"4acb23c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23e28da elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"23e28da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-book\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tContabilidade\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ac6450 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ac6450\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3b581a6\" data-id=\"3b581a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89c52bb elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"89c52bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-comments\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tContacto com o condom\u00ednio\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d78d5ac\" data-id=\"d78d5ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b0ac18 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9b0ac18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hammer\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tManuten\u00e7\u00e3o e repara\u00e7\u00e3o\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-bef341e\" data-id=\"bef341e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-565536e elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"565536e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tools\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTrabalhos de rotina\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-baa425c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"baa425c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19e9f89\" data-id=\"19e9f89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dc2b7f elementor-widget elementor-widget-spacer\" data-id=\"5dc2b7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59457eb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"59457eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0b20f41\" data-id=\"0b20f41\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5182020 elementor-widget elementor-widget-spacer\" data-id=\"5182020\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36851d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36851d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d936e3e\" data-id=\"d936e3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f1ba94 elementor-widget elementor-widget-spacer\" data-id=\"4f1ba94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-02ed83f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02ed83f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-466aba6\" data-id=\"466aba6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-475a300 elementor-widget elementor-widget-heading\" data-id=\"475a300\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Administra\u00e7\u00e3o de propriedade:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dc8a13 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5dc8a13\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cdf8d56\" data-id=\"cdf8d56\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-504a658 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"504a658\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-seedling\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tManuten\u00e7\u00e3o do jardim\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-05d7e33\" data-id=\"05d7e33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9f34b1 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d9f34b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-swimming-pool\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLimpeza regular e manuten\u00e7\u00e3o da piscina\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d623561\" data-id=\"d623561\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9372f33 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9372f33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-home\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPrepara\u00e7\u00e3o para check-ins e check-outs\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c0542ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c0542ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f5d2b37\" data-id=\"f5d2b37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f14db5 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9f14db5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-search\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tInspe\u00e7\u00f5es da propriedade\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-17cbe4f\" data-id=\"17cbe4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-598257a elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"598257a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-ad\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPromo\u00e7\u00e3o e publicidade\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-bf5cd1e\" data-id=\"bf5cd1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88bbc6d elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"88bbc6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAdministra\u00e7\u00e3o de alojamento para aluguer de f\u00e9rias\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-278c4f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"278c4f8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8afb274\" data-id=\"8afb274\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b202c4 elementor-widget elementor-widget-spacer\" data-id=\"2b202c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1615021 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1615021\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c8d53a\" data-id=\"2c8d53a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7a99ff elementor-widget elementor-widget-heading\" data-id=\"c7a99ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conhe\u00e7a mais sobre o nosso ADN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10be7e5 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10be7e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e8f3f8a\" data-id=\"e8f3f8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5e4da9 elementor-widget elementor-widget-spacer\" data-id=\"b5e4da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7b0b44 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7b0b44\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6abfa45\" data-id=\"6abfa45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abc511b elementor-widget elementor-widget-accordion\" data-id=\"abc511b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1801\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1801\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Miss\u00e3o<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1801\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1801\"><p>Nossa miss\u00e3o \u00e9 fornecer servi\u00e7os abrangentes de administra\u00e7\u00e3o de propriedades e aluguer de f\u00e9rias no Algarve para garantir tranquilidade e satisfa\u00e7\u00e3o aos propriet\u00e1rios. Procuramos oferecer solu\u00e7\u00f5es personalizadas e eficientes e cuidar de cada propriedade como se fosse nossa para assim proporcionar experi\u00eancias memor\u00e1veis aos h\u00f3spedes.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1802\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1802\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Vis\u00e3o<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1802\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1802\"><p>Sermos reconhecidos como uma empresa l\u00edder em administra\u00e7\u00e3o de propriedades e aluguer de f\u00e9rias no Algarve, pela excel\u00eancia dos nossos servi\u00e7os, pela qualidade das propriedades que representamos e pelo compromisso com a satisfa\u00e7\u00e3o dos propriet\u00e1rios e h\u00f3spedes. Procuramos constantemente aprimorar nossas opera\u00e7\u00f5es e expandir nossa presen\u00e7a ao estabelecer parcerias estrat\u00e9gicas e manter a confian\u00e7a e fidelidade dos nossos clientes.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1803\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1803\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Valores<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1803\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1803\"><p><b>Profissionalismo:<\/b> Atuamos com profissionalismo em todos os aspectos do nosso trabalho, desde o atendimento ao cliente at\u00e9 a manuten\u00e7\u00e3o das propriedades. Nossa conduta \u00e9 pautada pela \u00e9tica, integridade e respeito.<\/p><p><b>Excel\u00eancia:<\/b> Procuramos a excel\u00eancia em tudo o que fazemos para oferecer servi\u00e7os de alta qualidade, propriedades bem cuidadas e uma experi\u00eancia excepcional para os propriet\u00e1rios e h\u00f3spedes que confiam em n\u00f3s.<\/p><p><b>Dedica\u00e7\u00e3o:<\/b> Estamos comprometidos em cuidar das propriedades dos nossos clientes como se fossem nossas. Dedicamo-nos a manter um alto padr\u00e3o de servi\u00e7o, atendemos \u00e0s necessidades individuais de cada propriet\u00e1rio e garantimos que suas propriedades estejam bem administradas.<\/p><p><b>Confiabilidade:<\/b> Valorizamos a confian\u00e7a que nossos clientes depositam em n\u00f3s. Somos confi\u00e1veis e respons\u00e1veis em todas as nossas a\u00e7\u00f5es, cumprindo nossas obriga\u00e7\u00f5es com efici\u00eancia e transpar\u00eancia.<\/p><p><strong>Colabora\u00e7\u00e3o:<\/strong> Trabalhamos em estreita colabora\u00e7\u00e3o com nossos parceiros e clientes, valorizando suas contribui\u00e7\u00f5es para solu\u00e7\u00f5es conjuntas. Acreditamos no poder da colabora\u00e7\u00e3o para alcan\u00e7ar resultados superiores.<\/p><p><b>Melhoria cont\u00ednua:<\/b> Procuramos constantemente aprimorar nossos servi\u00e7os, processos e conhecimentos. Estamos abertos a feedback, aprendizado e inova\u00e7\u00e3o, para nos adaptarmos \u00e0s mudan\u00e7as do mercado e garantir a satisfa\u00e7\u00e3o cont\u00ednua de nossos clientes.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0c1806 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0c1806\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37a1caa\" data-id=\"37a1caa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af6172d elementor-widget elementor-widget-spacer\" data-id=\"af6172d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff93702 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"ff93702\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5e0c3d\" data-id=\"f5e0c3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-adfabff elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"adfabff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fale connosco<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63f2021 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63f2021\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-070ae9d\" data-id=\"070ae9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01b96bd elementor-widget elementor-widget-wpforms\" data-id=\"01b96bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-18389\"><form id=\"wpforms-form-18389\" class=\"wpforms-validate wpforms-form\" data-formid=\"18389\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/rentals\/pt-pt\/wp-json\/wp\/v2\/pages\/16612\" data-token=\"677989fd9a2c6ede7aa27dc960e178ac\" data-token-time=\"1788389162\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-18389-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-18389-field_1\">Nome (obrigat\u00f3rio) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-18389-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-18389-field_1-error\" required><\/div><div id=\"wpforms-18389-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-18389-field_2\">Email (obrigat\u00f3rio) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-18389-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-18389-field_2-error\" required><\/div><div id=\"wpforms-18389-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-18389-field_3\">Assunto<\/label><input type=\"text\" id=\"wpforms-18389-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-18389-field_3-error\" ><\/div><div id=\"wpforms-18389-field_4-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-18389-field_4\">Mensagem<\/label><textarea id=\"wpforms-18389-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" aria-errormessage=\"wpforms-18389-field_4-error\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"18389\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/pages\/16612\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-18389\" class=\"wpforms-submit\" data-alt-text=\"A enviar\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gabi Miguel Real Estate, Property Management &#038; Holiday Rentals Quer ajuda para rentabilizar, vender ou manter a sua propriedade? Conhe\u00e7a a Gabi Miguel. Fundada em 1987, a Gabi Miguel Lda est\u00e1 situada em Vale da Parra e se dedica a oferecer as melhores solu\u00e7\u00f5es para clientes na compra\/venda de im\u00f3veis, bem como no aluguer de &hellip; <a href=\"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/\" class=\"more-link\">Continuar a ler<span class=\"screen-reader-text\"> &#8220;About Us&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-wide-screen-page.php","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-16612","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Gabi Miguel Real Estate, Property Management &amp; Holiday Rentals Quer ajuda para rentabilizar, vender ou manter a sua propriedade? Conhe\u00e7a a Gabi Miguel. Fundada em 1987, a Gabi Miguel Lda est\u00e1 situada em Vale da Parra e se dedica a oferecer as melhores solu\u00e7\u00f5es para clientes na compra\/venda de im\u00f3veis, bem como no aluguer de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_PT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gabi Miguel Rentals \u2022 Your choice for all seasons\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"About Us | https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/\" \/>\n\t\t<meta property=\"og:description\" content=\"Gabi Miguel Real Estate, Property Management &amp; Holiday Rentals Quer ajuda para rentabilizar, vender ou manter a sua propriedade? Conhe\u00e7a a Gabi Miguel. Fundada em 1987, a Gabi Miguel Lda est\u00e1 situada em Vale da Parra e se dedica a oferecer as melhores solu\u00e7\u00f5es para clientes na compra\/venda de im\u00f3veis, bem como no aluguer de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"138\" \/>\n\t\t<meta property=\"og:image:height\" content=\"44\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-07T13:02:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-08-13T12:35:03+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gmholidayrentals\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"About Us | https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Gabi Miguel Real Estate, Property Management &amp; Holiday Rentals Quer ajuda para rentabilizar, vender ou manter a sua propriedade? Conhe\u00e7a a Gabi Miguel. Fundada em 1987, a Gabi Miguel Lda est\u00e1 situada em Vale da Parra e se dedica a oferecer as melhores solu\u00e7\u00f5es para clientes na compra\/venda de im\u00f3veis, bem como no aluguer de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/about-us\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/about-us\\\/#listItem\",\"name\":\"About Us\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/about-us\\\/#listItem\",\"position\":2,\"name\":\"About Us\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/#organization\",\"name\":\"Gabi Miguel\",\"description\":\"Your choice for all seasons\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/\",\"telephone\":\"+351289591378\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Gabi-Miguel-Holiday-Rentals.png\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/about-us\\\/#organizationLogo\",\"width\":138,\"height\":44},\"image\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/about-us\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gmholidayrentals\",\"https:\\\/\\\/www.instagram.com\\\/gm_holiday_rentals\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCcljMtn3tGtMKLrHu6bEgiA\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/gabimiguel\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/about-us\\\/#webpage\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/about-us\\\/\",\"name\":\"About Us | https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/about-us\\\/\",\"description\":\"Gabi Miguel Real Estate, Property Management & Holiday Rentals Quer ajuda para rentabilizar, vender ou manter a sua propriedade? Conhe\\u00e7a a Gabi Miguel. Fundada em 1987, a Gabi Miguel Lda est\\u00e1 situada em Vale da Parra e se dedica a oferecer as melhores solu\\u00e7\\u00f5es para clientes na compra\\\/venda de im\\u00f3veis, bem como no aluguer de\",\"inLanguage\":\"pt-PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/about-us\\\/#breadcrumblist\"},\"datePublished\":\"2023-06-07T13:02:33+00:00\",\"dateModified\":\"2024-08-13T12:35:03+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/\",\"name\":\"Gabi Miguel Holiday Rentals\",\"alternateName\":\"Gabi Miguel\",\"description\":\"Your choice for all seasons\",\"inLanguage\":\"pt-PT\",\"publisher\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/pt-pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"About Us | https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/","description":"Gabi Miguel Real Estate, Property Management & Holiday Rentals Quer ajuda para rentabilizar, vender ou manter a sua propriedade? Conhe\u00e7a a Gabi Miguel. Fundada em 1987, a Gabi Miguel Lda est\u00e1 situada em Vale da Parra e se dedica a oferecer as melhores solu\u00e7\u00f5es para clientes na compra\/venda de im\u00f3veis, bem como no aluguer de","canonical_url":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/#listItem","position":1,"name":"Home","item":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/#listItem","name":"About Us"}},{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/#listItem","position":2,"name":"About Us","previousItem":{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/#organization","name":"Gabi Miguel","description":"Your choice for all seasons","url":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/","telephone":"+351289591378","logo":{"@type":"ImageObject","url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/#organizationLogo","width":138,"height":44},"image":{"@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/gmholidayrentals","https:\/\/www.instagram.com\/gm_holiday_rentals\/","https:\/\/www.youtube.com\/channel\/UCcljMtn3tGtMKLrHu6bEgiA","https:\/\/www.linkedin.com\/in\/gabimiguel\/"]},{"@type":"WebPage","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/#webpage","url":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/","name":"About Us | https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/","description":"Gabi Miguel Real Estate, Property Management & Holiday Rentals Quer ajuda para rentabilizar, vender ou manter a sua propriedade? Conhe\u00e7a a Gabi Miguel. Fundada em 1987, a Gabi Miguel Lda est\u00e1 situada em Vale da Parra e se dedica a oferecer as melhores solu\u00e7\u00f5es para clientes na compra\/venda de im\u00f3veis, bem como no aluguer de","inLanguage":"pt-PT","isPartOf":{"@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/#website"},"breadcrumb":{"@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/#breadcrumblist"},"datePublished":"2023-06-07T13:02:33+00:00","dateModified":"2024-08-13T12:35:03+00:00"},{"@type":"WebSite","@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/#website","url":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/","name":"Gabi Miguel Holiday Rentals","alternateName":"Gabi Miguel","description":"Your choice for all seasons","inLanguage":"pt-PT","publisher":{"@id":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/#organization"}}]},"og:locale":"pt_PT","og:site_name":"Gabi Miguel Rentals \u2022 Your choice for all seasons","og:type":"article","og:title":"About Us | https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/","og:description":"Gabi Miguel Real Estate, Property Management &amp; Holiday Rentals Quer ajuda para rentabilizar, vender ou manter a sua propriedade? Conhe\u00e7a a Gabi Miguel. Fundada em 1987, a Gabi Miguel Lda est\u00e1 situada em Vale da Parra e se dedica a oferecer as melhores solu\u00e7\u00f5es para clientes na compra\/venda de im\u00f3veis, bem como no aluguer de","og:url":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/","og:image":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png","og:image:secure_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png","og:image:width":138,"og:image:height":44,"article:published_time":"2023-06-07T13:02:33+00:00","article:modified_time":"2024-08-13T12:35:03+00:00","article:publisher":"https:\/\/www.facebook.com\/gmholidayrentals","twitter:card":"summary_large_image","twitter:title":"About Us | https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/","twitter:description":"Gabi Miguel Real Estate, Property Management &amp; Holiday Rentals Quer ajuda para rentabilizar, vender ou manter a sua propriedade? Conhe\u00e7a a Gabi Miguel. Fundada em 1987, a Gabi Miguel Lda est\u00e1 situada em Vale da Parra e se dedica a oferecer as melhores solu\u00e7\u00f5es para clientes na compra\/venda de im\u00f3veis, bem como no aluguer de","twitter:image":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png"},"aioseo_meta_data":{"post_id":"16612","title":"About Us | #permalink","description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-30 20:40:55","updated":"2025-06-06 01:35:14","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAbout Us\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/"},{"label":"About Us","link":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/about-us\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/pages\/16612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/comments?post=16612"}],"version-history":[{"count":4,"href":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/pages\/16612\/revisions"}],"predecessor-version":[{"id":40727,"href":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/pages\/16612\/revisions\/40727"}],"wp:attachment":[{"href":"https:\/\/gabimiguel.pt\/rentals\/pt-pt\/wp-json\/wp\/v2\/media?parent=16612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}