
{"id":5557,"date":"2019-05-06T09:48:19","date_gmt":"2019-05-06T09:48:19","guid":{"rendered":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1.jpg"},"modified":"2019-05-06T09:48:19","modified_gmt":"2019-05-06T09:48:19","slug":"v4-gm-05-web-1-de-1","status":"inherit","type":"attachment","link":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/","title":{"rendered":"V4 GM 05 WEB (1 de 1)"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-5557","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gabi Miguel Rentals \u2022 Your choice for all seasons\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"V4 GM 05 WEB (1 de 1) \u2022 Gabi Miguel Rentals\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"138\" \/>\n\t\t<meta property=\"og:image:height\" content=\"44\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-05-06T09:48:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-05-06T09:48:19+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gmholidayrentals\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"V4 GM 05 WEB (1 de 1) \u2022 Gabi Miguel Rentals\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/accommodation\\\/villa-quinta-do-jolu\\\/v4-gm-05-web-1-de-1\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/accommodation\\\/villa-quinta-do-jolu\\\/v4-gm-05-web-1-de-1\\\/#listItem\",\"name\":\"V4 GM 05 WEB (1 de 1)\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/accommodation\\\/villa-quinta-do-jolu\\\/v4-gm-05-web-1-de-1\\\/#listItem\",\"position\":2,\"name\":\"V4 GM 05 WEB (1 de 1)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/accommodation\\\/villa-quinta-do-jolu\\\/v4-gm-05-web-1-de-1\\\/#itempage\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/accommodation\\\/villa-quinta-do-jolu\\\/v4-gm-05-web-1-de-1\\\/\",\"name\":\"V4 GM 05 WEB (1 de 1) \\u2022 Gabi Miguel Rentals\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/accommodation\\\/villa-quinta-do-jolu\\\/v4-gm-05-web-1-de-1\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2019-05-06T09:48:19+00:00\",\"dateModified\":\"2019-05-06T09:48:19+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/#organization\",\"name\":\"Gabi Miguel\",\"description\":\"Your choice for all seasons\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/\",\"telephone\":\"+351289591378\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Gabi-Miguel-Holiday-Rentals.png\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/accommodation\\\/villa-quinta-do-jolu\\\/v4-gm-05-web-1-de-1\\\/#organizationLogo\",\"width\":138,\"height\":44},\"image\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/accommodation\\\/villa-quinta-do-jolu\\\/v4-gm-05-web-1-de-1\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gmholidayrentals\",\"https:\\\/\\\/www.instagram.com\\\/gm_holiday_rentals\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCcljMtn3tGtMKLrHu6bEgiA\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/gabimiguel\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/author\\\/admin\\\/\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/accommodation\\\/villa-quinta-do-jolu\\\/v4-gm-05-web-1-de-1\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/068b65d24f062718562080b91a2711d10b0ceca66e352ff12b26021012f494c2?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Admin\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/#website\",\"url\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/\",\"name\":\"Gabi Miguel Holiday Rentals\",\"alternateName\":\"Gabi Miguel\",\"description\":\"Your choice for all seasons\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/gabimiguel.pt\\\/rentals\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"V4 GM 05 WEB (1 de 1) \u2022 Gabi Miguel Rentals","description":"","canonical_url":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals#listItem","position":1,"name":"Home","item":"https:\/\/gabimiguel.pt\/rentals","nextItem":{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/#listItem","name":"V4 GM 05 WEB (1 de 1)"}},{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/#listItem","position":2,"name":"V4 GM 05 WEB (1 de 1)","previousItem":{"@type":"ListItem","@id":"https:\/\/gabimiguel.pt\/rentals#listItem","name":"Home"}}]},{"@type":"ItemPage","@id":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/#itempage","url":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/","name":"V4 GM 05 WEB (1 de 1) \u2022 Gabi Miguel Rentals","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/gabimiguel.pt\/rentals\/#website"},"breadcrumb":{"@id":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/#breadcrumblist"},"author":{"@id":"https:\/\/gabimiguel.pt\/rentals\/author\/admin\/#author"},"creator":{"@id":"https:\/\/gabimiguel.pt\/rentals\/author\/admin\/#author"},"datePublished":"2019-05-06T09:48:19+00:00","dateModified":"2019-05-06T09:48:19+00:00"},{"@type":"Organization","@id":"https:\/\/gabimiguel.pt\/rentals\/#organization","name":"Gabi Miguel","description":"Your choice for all seasons","url":"https:\/\/gabimiguel.pt\/rentals\/","telephone":"+351289591378","logo":{"@type":"ImageObject","url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png","@id":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/#organizationLogo","width":138,"height":44},"image":{"@id":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/gmholidayrentals","https:\/\/www.instagram.com\/gm_holiday_rentals\/","https:\/\/www.youtube.com\/channel\/UCcljMtn3tGtMKLrHu6bEgiA","https:\/\/www.linkedin.com\/in\/gabimiguel\/"]},{"@type":"Person","@id":"https:\/\/gabimiguel.pt\/rentals\/author\/admin\/#author","url":"https:\/\/gabimiguel.pt\/rentals\/author\/admin\/","name":"Admin","image":{"@type":"ImageObject","@id":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/068b65d24f062718562080b91a2711d10b0ceca66e352ff12b26021012f494c2?s=96&d=mm&r=g","width":96,"height":96,"caption":"Admin"}},{"@type":"WebSite","@id":"https:\/\/gabimiguel.pt\/rentals\/#website","url":"https:\/\/gabimiguel.pt\/rentals\/","name":"Gabi Miguel Holiday Rentals","alternateName":"Gabi Miguel","description":"Your choice for all seasons","inLanguage":"en-US","publisher":{"@id":"https:\/\/gabimiguel.pt\/rentals\/#organization"}}]},"og:locale":"en_US","og:site_name":"Gabi Miguel Rentals \u2022 Your choice for all seasons","og:type":"article","og:title":"V4 GM 05 WEB (1 de 1) \u2022 Gabi Miguel Rentals","og:url":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/","og:image":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png","og:image:secure_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png","og:image:width":138,"og:image:height":44,"article:published_time":"2019-05-06T09:48:19+00:00","article:modified_time":"2019-05-06T09:48:19+00:00","article:publisher":"https:\/\/www.facebook.com\/gmholidayrentals","twitter:card":"summary_large_image","twitter:title":"V4 GM 05 WEB (1 de 1) \u2022 Gabi Miguel Rentals","twitter:image":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2023\/05\/cropped-Gabi-Miguel-Holiday-Rentals.png"},"aioseo_meta_data":{"post_id":"5557","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-09 15:08:21","updated":"2025-06-04 16:44:40","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gabimiguel.pt\/rentals\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tV4 GM 05 WEB (1 de 1)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/gabimiguel.pt\/rentals"},{"label":"V4 GM 05 WEB (1 de 1)","link":"https:\/\/gabimiguel.pt\/rentals\/accommodation\/villa-quinta-do-jolu\/v4-gm-05-web-1-de-1\/"}],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-300x201.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-300x201.jpg 300w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-768x516.jpg 768w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-1024x688.jpg 1024w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-920x618.jpg 920w, https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1.jpg 1899w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1899,"height":1275,"file":"2018\/07\/V4-GM-05-WEB-1-de-1.jpg","sizes":{"thumbnail":{"file":"V4-GM-05-WEB-1-de-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-150x150.jpg"},"medium":{"file":"V4-GM-05-WEB-1-de-1-300x201.jpg","width":300,"height":201,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-300x201.jpg"},"medium_large":{"file":"V4-GM-05-WEB-1-de-1-768x516.jpg","width":768,"height":516,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-768x516.jpg"},"large":{"file":"V4-GM-05-WEB-1-de-1-1024x688.jpg","width":1024,"height":688,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-1024x688.jpg"},"post-thumbnail":{"file":"V4-GM-05-WEB-1-de-1-1434x734.jpg","width":1434,"height":734,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-1434x734.jpg"},"villagio-thumb-medium":{"file":"V4-GM-05-WEB-1-de-1-920x618.jpg","width":920,"height":618,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-920x618.jpg"},"villagio-thumb-small":{"file":"V4-GM-05-WEB-1-de-1-717x540.jpg","width":717,"height":540,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-717x540.jpg"},"villagio-thumb-small-x2":{"file":"V4-GM-05-WEB-1-de-1-1434x1080.jpg","width":1434,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1-1434x1080.jpg"},"full":{"file":"V4-GM-05-WEB-1-de-1.jpg","width":1899,"height":1275,"mime_type":"image\/jpeg","source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1.jpg"}},"image_meta":{"aperture":"11","credit":"Mike Rijo","camera":"NIKON D750","caption":"","created_timestamp":"1556897468","copyright":"mikerijophoto.com","focal_length":"14","iso":"100","shutter_speed":"0.005","title":"","orientation":"0","keywords":[]}},"post":257,"source_url":"https:\/\/gabimiguel.pt\/rentals\/wp-content\/uploads\/2018\/07\/V4-GM-05-WEB-1-de-1.jpg","filename":"V4-GM-05-WEB-1-de-1.jpg","filesize":745318,"_links":{"self":[{"href":"https:\/\/gabimiguel.pt\/rentals\/wp-json\/wp\/v2\/media\/5557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gabimiguel.pt\/rentals\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/gabimiguel.pt\/rentals\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/gabimiguel.pt\/rentals\/wp-json\/wp\/v2\/users\/1"}],"wp:attached-to":[{"embeddable":true,"post_type":"mphb_room_type","id":257,"href":"https:\/\/gabimiguel.pt\/rentals\/wp-json\/wp\/v2\/mphb_room_type\/257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}